{"id":11960,"date":"2022-04-21T08:00:00","date_gmt":"2022-04-21T11:00:00","guid":{"rendered":"https:\/\/sempreit.com.br\/?p=11960"},"modified":"2022-03-31T14:59:51","modified_gmt":"2022-03-31T17:59:51","slug":"daas-flexibilidade","status":"publish","type":"post","link":"https:\/\/sempreit.com.br\/en\/daas-flexibilidade\/","title":{"rendered":"A flexibilidade que o DaaS pode oferecer"},"content":{"rendered":"<p>Com a evolu\u00e7\u00e3o da tecnologia, micro e pequenas empresas podem acessar ferramentas avan\u00e7adas para a automatizar os seus processos sem a necessidade de investir uma boa fatia do seu or\u00e7amento.<\/p>\n\n\n\n<p>Um dos maiores desafios na \u00e1rea de TI para os neg\u00f3cios, \u00e9 justamente a dificuldade em dimensionar as necessidades e compreender as reais demandas da empresa. O conceito de Device as a Service, DaaS, se prop\u00f5e a resolver esse problema.<\/p>\n\n\n\n<p>Com isso em mente, criamos um conte\u00fado exclusivo para que voc\u00ea compreenda como a sua empresa pode se tornar muito mais flex\u00edvel por meio dessa metodologia de infraestrutura de TI. Confira!<\/p>\n\n\n\n<p>Flexibilidade com DaaS<\/p>\n\n\n\n<p>O conceito de Device as a Service \u00e9 uma modalidade de presta\u00e7\u00e3o de servi\u00e7os na qual o produto \u00e9 um equipamento virtual em formato de assinatura. Trata-se de desktops e aplicativos que s\u00e3o necess\u00e1rios para que uma empresa funcione, por\u00e9m, de modo mais descentralizado com alta personaliza\u00e7\u00e3o.<\/p>\n\n\n\n<p>De acordo com dados compilados pela consultoria Gartner, espera-se que os custos com TI cres\u00e7am mais de 5% em 2022. Isso se deve aos reflexos da pandemia e a quebra na cadeia de suprimentos global, que est\u00e1 impactando diretamente a \u00e1rea da tecnologia.<\/p>\n\n\n\n<p>Paralelamente, pelas mesmas raz\u00f5es, o volume de pessoas trabalhando em home office, o que por um lado reduz os custos da empresa, aumenta o investimento necess\u00e1rio no setor.<\/p>\n\n\n\n<p>Conforme mat\u00e9ria do Jornal Cont\u00e1bil, ao ouvir especialistas, a empresa \u00e9 respons\u00e1vel pelas condi\u00e7\u00f5es de trabalho dos seus colaboradores, dessa maneira, precisa criar essa infraestrutura para migrar para uma realidade h\u00edbrida.<\/p>\n\n\n\n<p>Por\u00e9m, mesmo voltando com uma rotina integralmente presencial, diversas mudan\u00e7as ser\u00e3o necess\u00e1rias.<\/p>\n\n\n\n<p>Ao contratar um servi\u00e7o da modalidade DaaS, o gestor promove maior integra\u00e7\u00e3o entre esses colaboradores que est\u00e3o fora do escrit\u00f3rio.<\/p>\n\n\n\n<p>N\u00e3o \u00e9 mais necess\u00e1rio comprar equipamentos exclusivos para que os colaboradores levem para casa. \u00c9 poss\u00edvel criar um desktop hospedado em nuvem para que cada um utilize os mesmos recursos em locais distintos.<\/p>\n\n\n\n<p>Flexibiliza\u00e7\u00e3o, mas n\u00e3o da seguran\u00e7a<\/p>\n\n\n\n<p>Um dos maiores medos de todo gestor ao entregar os equipamentos para os colaboradores \u00e9 justamente em rela\u00e7\u00e3o \u00e0 seguran\u00e7a. N\u00e3o necessariamente do equipamento f\u00edsico, mas da informa\u00e7\u00e3o nele contida.<\/p>\n\n\n\n<p>Essa preocupa\u00e7\u00e3o \u00e9 leg\u00edtima e precisa ser observada para que os devidos protocolos e manuais de boas pr\u00e1ticas sejam criados.<\/p>\n\n\n\n<p>No entanto, existe um limite para isso. Quando a seguran\u00e7a \u00e9 excessiva, pode acabar gerando burocracia que trava os processos mais \u00e1geis.<\/p>\n\n\n\n<p>Por meio do DaaS, a sua empresa \u00e9 capaz de direcionar as autoriza\u00e7\u00f5es de uso com maior acerto. Cada colaborador recebe as suas credenciais, tendo o caminho livre para as aplica\u00e7\u00f5es e sistemas que competem \u00e0 sua atividade.<\/p>\n\n\n\n<p>Trata-se de um servi\u00e7o altamente personalizado no qual voc\u00ea s\u00f3 \u00e9 cobrado pelas fun\u00e7\u00f5es que efetivamente utilizar. Inclusive, \u00e9 poss\u00edvel configurar duas modalidades de DaaS de acordo com as necessidades.<\/p>\n\n\n\n<p>Desktop Persistente<\/p>\n\n\n\n<p>O desktop persistente \u00e9 aquele recomendado para ser usado pelos colaboradores que necessitam de mais funcionalidades que precisam estar dispon\u00edveis de modo ininterrupto. Por exemplo, softwares que armazenam informa\u00e7\u00f5es na pr\u00f3pria m\u00e1quina.<\/p>\n\n\n\n<p>Quando o seu desktop \u00e9 persistente, significa que ao desligar o equipamento, ligando outra vez, ter\u00e1 exatamente a mesma tela que deixou para tr\u00e1s. Assim, os documentos e arquivos salvos estar\u00e3o nas pastas definidas de acordo com os caminhos pr\u00e9-estabelecidos.<\/p>\n\n\n\n<p>Normalmente \u00e9 \u00fatil para as m\u00e1quinas mais centrais nos processos.<\/p>\n\n\n\n<p>Desktop n\u00e3o-persistente<\/p>\n\n\n\n<p>Essa modalidade \u00e9 mais recomendada para as tarefas mais perif\u00e9ricas nos processos. Ou seja, para os trabalhadores tempor\u00e1rios, estagi\u00e1rios ou at\u00e9 mesmo prestadores de servi\u00e7os externos.<\/p>\n\n\n\n<p>Uma vez que o computador \u00e9 desligado, toda a informa\u00e7\u00e3o armazenada \u00e9 apagada. Ou seja, para se ter acesso a um determinado documento, ser\u00e1 preciso salvar na nuvem para que seja poss\u00edvel recuperar em outro momento.<\/p>\n\n\n\n<p>A modalidade persistente envolve uma capacidade de armazenamento muito mais significativa, enquanto o n\u00e3o-persistente pode ser utilizado at\u00e9 mesmo em equipamentos mais simples e com menos poder de processamento.<\/p>\n\n\n\n<p>Acesso multiplataformas<\/p>\n\n\n\n<p>Ao contr\u00e1rio do que muitas pessoas pensam, quando falamos em desktop estamos falando em uma \u00e1rea de trabalho que n\u00e3o est\u00e1 restrita apenas aos computadores. Todo equipamento digital com suporte HTML5 pode se tornar uma esta\u00e7\u00e3o de trabalho segura, criptografada e confi\u00e1vel.<\/p>\n\n\n\n<p>Ou seja, o pr\u00f3prio gestor pode, por meio do seu smartphone ou tablet, acessar a sua \u00e1rea de trabalho para resolver quest\u00f5es pendentes onde quer que esteja, bastando uma conex\u00e3o est\u00e1vel com a internet.<\/p>\n\n\n\n<p>Ainda, o suporte \u00e9 remoto, de modo que os colaboradores n\u00e3o precisam interromper as suas atividades para realizar uma atualiza\u00e7\u00e3o no sistema ou em seus softwares. Paralelamente, h\u00e1 vias de contato dispon\u00edveis para a solu\u00e7\u00e3o \u00e1gil e assertiva de problemas.<\/p>\n\n\n\n<p>Aqui na Sempre IT n\u00f3s contamos com um servi\u00e7o exclusivo de DaaS que est\u00e1 alinhado com a nossa Jornada do Lobo, de modo que podemos fornecer uma vis\u00e3o geral da sua \u00e1rea de TI para otimizar a tomada de decis\u00f5es sobre o setor.<\/p>\n\n\n\n<p>Entre em contato pelo WhatsApp para tirar todas as suas d\u00favidas sobre a nossa solu\u00e7\u00e3o!<\/p>","protected":false},"excerpt":{"rendered":"<p>Com a evolu\u00e7\u00e3o da tecnologia, micro e pequenas empresas podem acessar ferramentas avan\u00e7adas para a automatizar os seus processos sem a necessidade de investir uma boa fatia do seu or\u00e7amento. Um dos maiores desafios na \u00e1rea de TI para os neg\u00f3cios, \u00e9 justamente a dificuldade em dimensionar as necessidades e compreender as reais demandas da [&hellip;]<\/p>\n","protected":false},"author":15,"featured_media":11961,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[73],"tags":[],"destaque_blog":[],"class_list":["post-11960","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-daas"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>A flexibilidade que o DaaS pode oferecer | Sempre IT<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sempreit.com.br\/en\/daas-flexibilidade\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A flexibilidade que o DaaS pode oferecer | Sempre IT\" \/>\n<meta property=\"og:description\" content=\"Com a evolu\u00e7\u00e3o da tecnologia, micro e pequenas empresas podem acessar ferramentas avan\u00e7adas para a automatizar os seus processos sem a necessidade de investir uma boa fatia do seu or\u00e7amento. Um dos maiores desafios na \u00e1rea de TI para os neg\u00f3cios, \u00e9 justamente a dificuldade em dimensionar as necessidades e compreender as reais demandas da [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sempreit.com.br\/en\/daas-flexibilidade\/\" \/>\n<meta property=\"og:site_name\" content=\"Sempre IT\" \/>\n<meta property=\"article:published_time\" content=\"2022-04-21T11:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sempreit.com.br\/wp-content\/uploads\/2022\/03\/DaaS-Flex.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"410\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"sempre it\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"sempre it\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/sempreit.com.br\/daas-flexibilidade\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/sempreit.com.br\/daas-flexibilidade\/\"},\"author\":{\"name\":\"sempre it\",\"@id\":\"https:\/\/sempreit.com.br\/#\/schema\/person\/c631a19da2b52ca31140d6dd158ffcbf\"},\"headline\":\"A flexibilidade que o DaaS pode oferecer\",\"datePublished\":\"2022-04-21T11:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/sempreit.com.br\/daas-flexibilidade\/\"},\"wordCount\":883,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/sempreit.com.br\/#organization\"},\"image\":{\"@id\":\"https:\/\/sempreit.com.br\/daas-flexibilidade\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/sempreit.com.br\/wp-content\/uploads\/2022\/03\/DaaS-Flex.jpg\",\"articleSection\":[\"DaaS\"],\"inLanguage\":\"en\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/sempreit.com.br\/daas-flexibilidade\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/sempreit.com.br\/daas-flexibilidade\/\",\"url\":\"https:\/\/sempreit.com.br\/daas-flexibilidade\/\",\"name\":\"A flexibilidade que o DaaS pode oferecer | Sempre IT\",\"isPartOf\":{\"@id\":\"https:\/\/sempreit.com.br\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/sempreit.com.br\/daas-flexibilidade\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/sempreit.com.br\/daas-flexibilidade\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/sempreit.com.br\/wp-content\/uploads\/2022\/03\/DaaS-Flex.jpg\",\"datePublished\":\"2022-04-21T11:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/sempreit.com.br\/daas-flexibilidade\/#breadcrumb\"},\"inLanguage\":\"en\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/sempreit.com.br\/daas-flexibilidade\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en\",\"@id\":\"https:\/\/sempreit.com.br\/daas-flexibilidade\/#primaryimage\",\"url\":\"https:\/\/sempreit.com.br\/wp-content\/uploads\/2022\/03\/DaaS-Flex.jpg\",\"contentUrl\":\"https:\/\/sempreit.com.br\/wp-content\/uploads\/2022\/03\/DaaS-Flex.jpg\",\"width\":640,\"height\":410},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/sempreit.com.br\/daas-flexibilidade\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/sempreit.com.br\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A flexibilidade que o DaaS pode oferecer\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/sempreit.com.br\/#website\",\"url\":\"https:\/\/sempreit.com.br\/\",\"name\":\"Sempre IT\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/sempreit.com.br\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/sempreit.com.br\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/sempreit.com.br\/#organization\",\"name\":\"Sempre IT\",\"url\":\"https:\/\/sempreit.com.br\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en\",\"@id\":\"https:\/\/sempreit.com.br\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/sempreit.com.br\/wp-content\/uploads\/2025\/12\/Lobo.png\",\"contentUrl\":\"https:\/\/sempreit.com.br\/wp-content\/uploads\/2025\/12\/Lobo.png\",\"width\":552,\"height\":677,\"caption\":\"Sempre IT\"},\"image\":{\"@id\":\"https:\/\/sempreit.com.br\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/sempreit.com.br\/#\/schema\/person\/c631a19da2b52ca31140d6dd158ffcbf\",\"name\":\"sempre it\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en\",\"@id\":\"https:\/\/sempreit.com.br\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/sempreit.com.br\/wp-content\/litespeed\/avatar\/64d26965cced0bf8232cfabd45c73828.jpg?ver=1777908584\",\"contentUrl\":\"https:\/\/sempreit.com.br\/wp-content\/litespeed\/avatar\/64d26965cced0bf8232cfabd45c73828.jpg?ver=1777908584\",\"caption\":\"sempre it\"},\"url\":\"https:\/\/sempreit.com.br\/en\/author\/sempreit\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"A flexibilidade que o DaaS pode oferecer | Sempre IT","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sempreit.com.br\/en\/daas-flexibilidade\/","og_locale":"en_US","og_type":"article","og_title":"A flexibilidade que o DaaS pode oferecer | Sempre IT","og_description":"Com a evolu\u00e7\u00e3o da tecnologia, micro e pequenas empresas podem acessar ferramentas avan\u00e7adas para a automatizar os seus processos sem a necessidade de investir uma boa fatia do seu or\u00e7amento. Um dos maiores desafios na \u00e1rea de TI para os neg\u00f3cios, \u00e9 justamente a dificuldade em dimensionar as necessidades e compreender as reais demandas da [&hellip;]","og_url":"https:\/\/sempreit.com.br\/en\/daas-flexibilidade\/","og_site_name":"Sempre IT","article_published_time":"2022-04-21T11:00:00+00:00","og_image":[{"width":640,"height":410,"url":"https:\/\/sempreit.com.br\/wp-content\/uploads\/2022\/03\/DaaS-Flex.jpg","type":"image\/jpeg"}],"author":"sempre it","twitter_card":"summary_large_image","twitter_misc":{"Written by":"sempre it","Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sempreit.com.br\/daas-flexibilidade\/#article","isPartOf":{"@id":"https:\/\/sempreit.com.br\/daas-flexibilidade\/"},"author":{"name":"sempre it","@id":"https:\/\/sempreit.com.br\/#\/schema\/person\/c631a19da2b52ca31140d6dd158ffcbf"},"headline":"A flexibilidade que o DaaS pode oferecer","datePublished":"2022-04-21T11:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/sempreit.com.br\/daas-flexibilidade\/"},"wordCount":883,"commentCount":0,"publisher":{"@id":"https:\/\/sempreit.com.br\/#organization"},"image":{"@id":"https:\/\/sempreit.com.br\/daas-flexibilidade\/#primaryimage"},"thumbnailUrl":"https:\/\/sempreit.com.br\/wp-content\/uploads\/2022\/03\/DaaS-Flex.jpg","articleSection":["DaaS"],"inLanguage":"en","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/sempreit.com.br\/daas-flexibilidade\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/sempreit.com.br\/daas-flexibilidade\/","url":"https:\/\/sempreit.com.br\/daas-flexibilidade\/","name":"A flexibilidade que o DaaS pode oferecer | Sempre IT","isPartOf":{"@id":"https:\/\/sempreit.com.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sempreit.com.br\/daas-flexibilidade\/#primaryimage"},"image":{"@id":"https:\/\/sempreit.com.br\/daas-flexibilidade\/#primaryimage"},"thumbnailUrl":"https:\/\/sempreit.com.br\/wp-content\/uploads\/2022\/03\/DaaS-Flex.jpg","datePublished":"2022-04-21T11:00:00+00:00","breadcrumb":{"@id":"https:\/\/sempreit.com.br\/daas-flexibilidade\/#breadcrumb"},"inLanguage":"en","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sempreit.com.br\/daas-flexibilidade\/"]}]},{"@type":"ImageObject","inLanguage":"en","@id":"https:\/\/sempreit.com.br\/daas-flexibilidade\/#primaryimage","url":"https:\/\/sempreit.com.br\/wp-content\/uploads\/2022\/03\/DaaS-Flex.jpg","contentUrl":"https:\/\/sempreit.com.br\/wp-content\/uploads\/2022\/03\/DaaS-Flex.jpg","width":640,"height":410},{"@type":"BreadcrumbList","@id":"https:\/\/sempreit.com.br\/daas-flexibilidade\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/sempreit.com.br\/"},{"@type":"ListItem","position":2,"name":"A flexibilidade que o DaaS pode oferecer"}]},{"@type":"WebSite","@id":"https:\/\/sempreit.com.br\/#website","url":"https:\/\/sempreit.com.br\/","name":"Sempre IT","description":"","publisher":{"@id":"https:\/\/sempreit.com.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sempreit.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en"},{"@type":"Organization","@id":"https:\/\/sempreit.com.br\/#organization","name":"Sempre IT","url":"https:\/\/sempreit.com.br\/","logo":{"@type":"ImageObject","inLanguage":"en","@id":"https:\/\/sempreit.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/sempreit.com.br\/wp-content\/uploads\/2025\/12\/Lobo.png","contentUrl":"https:\/\/sempreit.com.br\/wp-content\/uploads\/2025\/12\/Lobo.png","width":552,"height":677,"caption":"Sempre IT"},"image":{"@id":"https:\/\/sempreit.com.br\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/sempreit.com.br\/#\/schema\/person\/c631a19da2b52ca31140d6dd158ffcbf","name":"sempre it","image":{"@type":"ImageObject","inLanguage":"en","@id":"https:\/\/sempreit.com.br\/#\/schema\/person\/image\/","url":"https:\/\/sempreit.com.br\/wp-content\/litespeed\/avatar\/64d26965cced0bf8232cfabd45c73828.jpg?ver=1777908584","contentUrl":"https:\/\/sempreit.com.br\/wp-content\/litespeed\/avatar\/64d26965cced0bf8232cfabd45c73828.jpg?ver=1777908584","caption":"sempre it"},"url":"https:\/\/sempreit.com.br\/en\/author\/sempreit\/"}]}},"_links":{"self":[{"href":"https:\/\/sempreit.com.br\/en\/wp-json\/wp\/v2\/posts\/11960","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sempreit.com.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sempreit.com.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sempreit.com.br\/en\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/sempreit.com.br\/en\/wp-json\/wp\/v2\/comments?post=11960"}],"version-history":[{"count":1,"href":"https:\/\/sempreit.com.br\/en\/wp-json\/wp\/v2\/posts\/11960\/revisions"}],"predecessor-version":[{"id":11962,"href":"https:\/\/sempreit.com.br\/en\/wp-json\/wp\/v2\/posts\/11960\/revisions\/11962"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sempreit.com.br\/en\/wp-json\/wp\/v2\/media\/11961"}],"wp:attachment":[{"href":"https:\/\/sempreit.com.br\/en\/wp-json\/wp\/v2\/media?parent=11960"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sempreit.com.br\/en\/wp-json\/wp\/v2\/categories?post=11960"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sempreit.com.br\/en\/wp-json\/wp\/v2\/tags?post=11960"},{"taxonomy":"destaque_blog","embeddable":true,"href":"https:\/\/sempreit.com.br\/en\/wp-json\/wp\/v2\/destaque_blog?post=11960"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}